{"id":3436,"date":"2026-01-09T13:31:01","date_gmt":"2026-01-09T12:31:01","guid":{"rendered":"https:\/\/www.boomerang-intelligence.com\/?p=3436"},"modified":"2026-01-09T13:31:01","modified_gmt":"2026-01-09T12:31:01","slug":"6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer","status":"publish","type":"post","link":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/","title":{"rendered":"6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer"},"content":{"rendered":"<p data-start=\"533\" data-end=\"755\">Actualmente, todas las empresas buscan incorporar a sus equipos <strong data-start=\"597\" data-end=\"635\">los mejores perfiles profesionales<\/strong>, personas que no solo encajen en el puesto de trabajo, sino tambi\u00e9n en la <strong data-start=\"710\" data-end=\"754\">cultura y los valores de la organizaci\u00f3n<\/strong>.<\/p>\n<p data-start=\"757\" data-end=\"981\">Aunque encontrar al candidato ideal no es un proceso sencillo, hoy existen <strong data-start=\"832\" data-end=\"873\">t\u00e9cnicas y herramientas de recruiting<\/strong> que permiten optimizar el proceso de selecci\u00f3n, reducir tiempos y mejorar la calidad de las contrataciones.<\/p>\n<p data-start=\"983\" data-end=\"1178\">Dependiendo del tipo de vacante y del \u00e1rea (IT\/Tech, Legal, Finance, Sales, Marketing, RRHH, etc.), es recomendable utilizar <strong data-start=\"1108\" data-end=\"1145\">t\u00e9cnicas diferentes o combinarlas<\/strong> para obtener mejores resultados.<\/p>\n<p data-start=\"1180\" data-end=\"1300\">A continuaci\u00f3n, te presentamos algunas de las <strong data-start=\"1226\" data-end=\"1299\">t\u00e9cnicas de reclutamiento m\u00e1s utilizadas y efectivas en la actualidad<\/strong>.<\/p>\n<hr data-start=\"1302\" data-end=\"1305\" \/>\n<h2 data-start=\"1307\" data-end=\"1359\">T\u00e9cnicas innovadoras de reclutamiento y selecci\u00f3n<\/h2>\n<h3 data-start=\"1361\" data-end=\"1407\">1. Gamificaci\u00f3n en el proceso de selecci\u00f3n<\/h3>\n<p data-start=\"1409\" data-end=\"1633\">La <strong data-start=\"1412\" data-end=\"1428\">gamificaci\u00f3n<\/strong> es una de las t\u00e9cnicas de recruiting m\u00e1s exitosas y utilizadas en los \u00faltimos a\u00f1os. Consiste en aplicar din\u00e1micas de juego para evaluar a los candidatos de forma m\u00e1s <strong data-start=\"1595\" data-end=\"1632\">interactiva, objetiva y atractiva<\/strong>.<\/p>\n<p data-start=\"1635\" data-end=\"1669\">Este tipo de herramientas permite:<\/p>\n<ul data-start=\"1670\" data-end=\"1855\">\n<li data-start=\"1670\" data-end=\"1731\">\n<p data-start=\"1672\" data-end=\"1731\">Evaluar habilidades t\u00e9cnicas y competencias transversales<\/p>\n<\/li>\n<li data-start=\"1732\" data-end=\"1790\">\n<p data-start=\"1734\" data-end=\"1790\">Analizar la toma de decisiones ante situaciones reales<\/p>\n<\/li>\n<li data-start=\"1791\" data-end=\"1855\">\n<p data-start=\"1793\" data-end=\"1855\">Observar la reacci\u00f3n del candidato ante distintos escenarios<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1857\" data-end=\"1991\">Es especialmente \u00fatil en procesos masivos o en posiciones donde se requiere pensamiento l\u00f3gico, creatividad o resoluci\u00f3n de problemas.<\/p>\n<hr data-start=\"1993\" data-end=\"1996\" \/>\n<h3 data-start=\"1998\" data-end=\"2036\">2. Videoentrevistas en tiempo real<\/h3>\n<p data-start=\"2038\" data-end=\"2253\">Cada vez m\u00e1s empresas apuestan por las <strong data-start=\"2077\" data-end=\"2097\">videoentrevistas<\/strong> a trav\u00e9s de plataformas como Microsoft Teams, Zoom o Google Meet, especialmente en procesos de selecci\u00f3n masivos o con candidatos en distintas ubicaciones.<\/p>\n<p data-start=\"2255\" data-end=\"2285\">Las videoentrevistas permiten:<\/p>\n<ul data-start=\"2286\" data-end=\"2407\">\n<li data-start=\"2286\" data-end=\"2328\">\n<p data-start=\"2288\" data-end=\"2328\">Evaluar el lenguaje verbal y no verbal<\/p>\n<\/li>\n<li data-start=\"2329\" data-end=\"2368\">\n<p data-start=\"2331\" data-end=\"2368\">Realizar un primer filtro eficiente<\/p>\n<\/li>\n<li data-start=\"2369\" data-end=\"2407\">\n<p data-start=\"2371\" data-end=\"2407\">Ahorrar tiempo y costes log\u00edsticos<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2409\" data-end=\"2545\">Adem\u00e1s, facilitan avanzar posteriormente a entrevistas m\u00e1s profundas, presenciales o virtuales, solo con los candidatos mejor alineados.<\/p>\n<hr data-start=\"2547\" data-end=\"2550\" \/>\n<h3 data-start=\"2552\" data-end=\"2587\">3. Videoentrevistas pregrabadas<\/h3>\n<p data-start=\"2589\" data-end=\"2700\">Las <strong data-start=\"2593\" data-end=\"2629\">entrevistas en v\u00eddeo pregrabadas<\/strong> suponen un gran ahorro de tiempo para los equipos de Recursos Humanos.<\/p>\n<p data-start=\"2702\" data-end=\"2725\">El proceso consiste en:<\/p>\n<ul data-start=\"2726\" data-end=\"2841\">\n<li data-start=\"2726\" data-end=\"2778\">\n<p data-start=\"2728\" data-end=\"2778\">Grabar una serie de preguntas clave una sola vez<\/p>\n<\/li>\n<li data-start=\"2779\" data-end=\"2841\">\n<p data-start=\"2781\" data-end=\"2841\">Permitir que los candidatos respondan de forma asincr\u00f3nica<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2843\" data-end=\"2865\">Esta t\u00e9cnica facilita:<\/p>\n<ul data-start=\"2866\" data-end=\"2984\">\n<li data-start=\"2866\" data-end=\"2893\">\n<p data-start=\"2868\" data-end=\"2893\">Un primer filtro r\u00e1pido<\/p>\n<\/li>\n<li data-start=\"2894\" data-end=\"2936\">\n<p data-start=\"2896\" data-end=\"2936\">Comparar respuestas de forma homog\u00e9nea<\/p>\n<\/li>\n<li data-start=\"2937\" data-end=\"2984\">\n<p data-start=\"2939\" data-end=\"2984\">Evaluar comunicaci\u00f3n, claridad y motivaci\u00f3n<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2986\" data-end=\"3045\">Es ideal para procesos con un alto volumen de candidaturas.<\/p>\n<hr data-start=\"3047\" data-end=\"3050\" \/>\n<h3 data-start=\"3052\" data-end=\"3112\">4. Reclutamiento inteligente con inteligencia artificial<\/h3>\n<p data-start=\"3114\" data-end=\"3335\">El <strong data-start=\"3117\" data-end=\"3146\">reclutamiento inteligente<\/strong>, apoyado en algoritmos de <strong data-start=\"3173\" data-end=\"3200\">inteligencia artificial<\/strong>, permite analizar grandes vol\u00famenes de informaci\u00f3n y cruzar datos para identificar a los candidatos que mejor encajan con una vacante.<\/p>\n<p data-start=\"3337\" data-end=\"3365\">Estas herramientas ayudan a:<\/p>\n<ul data-start=\"3366\" data-end=\"3478\">\n<li data-start=\"3366\" data-end=\"3409\">\n<p data-start=\"3368\" data-end=\"3409\">Filtrar perfiles seg\u00fan requisitos clave<\/p>\n<\/li>\n<li data-start=\"3410\" data-end=\"3428\">\n<p data-start=\"3412\" data-end=\"3428\">Reducir sesgos<\/p>\n<\/li>\n<li data-start=\"3429\" data-end=\"3478\">\n<p data-start=\"3431\" data-end=\"3478\">Mejorar la precisi\u00f3n del proceso de selecci\u00f3n<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"3480\" data-end=\"3808\">Por este motivo, cada vez m\u00e1s empresas <strong data-start=\"3519\" data-end=\"3562\">externalizan sus procesos de recruiting<\/strong> a plataformas especializadas como <strong data-start=\"3597\" data-end=\"3623\">Boomerang Intelligence<\/strong>, que combinan tecnolog\u00eda avanzada con el conocimiento de recruiters expertos para cubrir posiciones en <strong data-start=\"3727\" data-end=\"3770\">todas las \u00e1reas y niveles profesionales<\/strong>, en menos tiempo y con mayor calidad.<\/p>\n<hr data-start=\"3810\" data-end=\"3813\" \/>\n<h3 data-start=\"3815\" data-end=\"3840\">5. Inbound Recruiting<\/h3>\n<p data-start=\"3842\" data-end=\"3992\">El <strong data-start=\"3845\" data-end=\"3867\">Inbound Recruiting<\/strong> aplica estrategias de marketing para atraer talento, incluso candidatos que no est\u00e1n buscando activamente un cambio laboral.<\/p>\n<p data-start=\"3994\" data-end=\"4022\">Esta metodolog\u00eda se basa en:<\/p>\n<ul data-start=\"4023\" data-end=\"4175\">\n<li data-start=\"4023\" data-end=\"4074\">\n<p data-start=\"4025\" data-end=\"4074\">Contenidos en redes sociales y medios digitales<\/p>\n<\/li>\n<li data-start=\"4075\" data-end=\"4124\">\n<p data-start=\"4077\" data-end=\"4124\">Comunicaci\u00f3n de valores, cultura y beneficios<\/p>\n<\/li>\n<li data-start=\"4125\" data-end=\"4175\">\n<p data-start=\"4127\" data-end=\"4175\">Construcci\u00f3n de una marca empleadora atractiva<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"4177\" data-end=\"4315\">El objetivo es que sean los propios candidatos quienes se interesen por la empresa y se acerquen de forma natural al proceso de selecci\u00f3n.<\/p>\n<hr data-start=\"4317\" data-end=\"4320\" \/>\n<h3 data-start=\"4322\" data-end=\"4345\">6. Curr\u00edculum ciego<\/h3>\n<p data-start=\"4347\" data-end=\"4459\">El <strong data-start=\"4350\" data-end=\"4370\">curr\u00edculum ciego<\/strong> es una t\u00e9cnica que busca eliminar sesgos en las primeras fases del proceso de selecci\u00f3n.<\/p>\n<p data-start=\"4461\" data-end=\"4528\">Consiste en evaluar a los candidatos sin informaci\u00f3n personal como:<\/p>\n<ul data-start=\"4529\" data-end=\"4589\">\n<li data-start=\"4529\" data-end=\"4539\">\n<p data-start=\"4531\" data-end=\"4539\">Nombre<\/p>\n<\/li>\n<li data-start=\"4540\" data-end=\"4548\">\n<p data-start=\"4542\" data-end=\"4548\">Edad<\/p>\n<\/li>\n<li data-start=\"4549\" data-end=\"4559\">\n<p data-start=\"4551\" data-end=\"4559\">G\u00e9nero<\/p>\n<\/li>\n<li data-start=\"4560\" data-end=\"4589\">\n<p data-start=\"4562\" data-end=\"4589\">Nacionalidad o fotograf\u00eda<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"4591\" data-end=\"4639\">De este modo, el foco se pone exclusivamente en:<\/p>\n<ul data-start=\"4640\" data-end=\"4685\">\n<li data-start=\"4640\" data-end=\"4655\">\n<p data-start=\"4642\" data-end=\"4655\">Habilidades<\/p>\n<\/li>\n<li data-start=\"4656\" data-end=\"4671\">\n<p data-start=\"4658\" data-end=\"4671\">Experiencia<\/p>\n<\/li>\n<li data-start=\"4672\" data-end=\"4685\">\n<p data-start=\"4674\" data-end=\"4685\">Formaci\u00f3n<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"4687\" data-end=\"4766\">Esta metodolog\u00eda promueve procesos m\u00e1s <strong data-start=\"4726\" data-end=\"4765\">objetivos, inclusivos y equitativos<\/strong>.<\/p>\n<hr data-start=\"4768\" data-end=\"4771\" \/>\n<h2 data-start=\"4773\" data-end=\"4786\">Conclusi\u00f3n<\/h2>\n<p data-start=\"4788\" data-end=\"5067\">Las t\u00e9cnicas de reclutamiento y selecci\u00f3n han evolucionado para adaptarse a un mercado laboral cada vez m\u00e1s competitivo y din\u00e1mico. La combinaci\u00f3n de <strong data-start=\"4938\" data-end=\"4991\">tecnolog\u00eda, estrategia y conocimiento del mercado<\/strong> permite a las empresas atraer y seleccionar talento de forma m\u00e1s eficiente.<\/p>\n<p data-start=\"5069\" data-end=\"5394\">En <strong data-start=\"5072\" data-end=\"5098\">Boomerang Intelligence<\/strong>, ayudamos a las organizaciones a dise\u00f1ar y ejecutar procesos de recruiting inteligentes, combinando <strong data-start=\"5199\" data-end=\"5254\">inteligencia artificial y recruiters especializados<\/strong>, para cubrir posiciones en <strong data-start=\"5282\" data-end=\"5326\">todas las verticales y \u00e1reas funcionales<\/strong>, de forma r\u00e1pida, eficaz y alineada con la cultura de cada empresa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actualmente, todas las empresas buscan incorporar a sus equipos los mejores perfiles profesionales, personas que no solo encajen en el puesto de trabajo, sino tambi\u00e9n en la cultura y los valores de la organizaci\u00f3n. Aunque encontrar al candidato ideal no es un proceso sencillo, hoy existen t\u00e9cnicas y herramientas de recruiting que permiten optimizar el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3437,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-3436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rrhh"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer - Boomerang Intelligence<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer - Boomerang Intelligence\" \/>\n<meta property=\"og:description\" content=\"Actualmente, todas las empresas buscan incorporar a sus equipos los mejores perfiles profesionales, personas que no solo encajen en el puesto de trabajo, sino tambi\u00e9n en la cultura y los valores de la organizaci\u00f3n. Aunque encontrar al candidato ideal no es un proceso sencillo, hoy existen t\u00e9cnicas y herramientas de recruiting que permiten optimizar el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/\" \/>\n<meta property=\"og:site_name\" content=\"Boomerang Intelligence\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-09T12:31:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.boomerang-intelligence.com\/wp-content\/uploads\/2026\/01\/146-Conoce-las-nuevas-tecnicas-de-seleccion-de-personal-1024x576-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Denis Pereta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Denis Pereta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/\"},\"author\":{\"name\":\"Denis Pereta\",\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/#\\\/schema\\\/person\\\/b24d3c90f2bee8ea7a717afb3e0a3855\"},\"headline\":\"6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer\",\"datePublished\":\"2026-01-09T12:31:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/\"},\"wordCount\":730,\"publisher\":{\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/146-Conoce-las-nuevas-tecnicas-de-seleccion-de-personal-1024x576-1.png\",\"articleSection\":[\"RRHH\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/\",\"url\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/\",\"name\":\"6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer - Boomerang Intelligence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/146-Conoce-las-nuevas-tecnicas-de-seleccion-de-personal-1024x576-1.png\",\"datePublished\":\"2026-01-09T12:31:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/146-Conoce-las-nuevas-tecnicas-de-seleccion-de-personal-1024x576-1.png\",\"contentUrl\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/146-Conoce-las-nuevas-tecnicas-de-seleccion-de-personal-1024x576-1.png\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/rrhh\\\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/\",\"name\":\"Boomerang Intelligence\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/#organization\",\"name\":\"Boomerang Intelligence\",\"url\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo_boomerang_intelligence.png\",\"contentUrl\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo_boomerang_intelligence.png\",\"width\":504,\"height\":130,\"caption\":\"Boomerang Intelligence\"},\"image\":{\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/#\\\/schema\\\/person\\\/b24d3c90f2bee8ea7a717afb3e0a3855\",\"name\":\"Denis Pereta\",\"url\":\"https:\\\/\\\/www.boomerang-intelligence.com\\\/ca\\\/blog\\\/author\\\/denis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer - Boomerang Intelligence","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/","og_locale":"ca_ES","og_type":"article","og_title":"6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer - Boomerang Intelligence","og_description":"Actualmente, todas las empresas buscan incorporar a sus equipos los mejores perfiles profesionales, personas que no solo encajen en el puesto de trabajo, sino tambi\u00e9n en la cultura y los valores de la organizaci\u00f3n. Aunque encontrar al candidato ideal no es un proceso sencillo, hoy existen t\u00e9cnicas y herramientas de recruiting que permiten optimizar el [&hellip;]","og_url":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/","og_site_name":"Boomerang Intelligence","article_published_time":"2026-01-09T12:31:01+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.boomerang-intelligence.com\/wp-content\/uploads\/2026\/01\/146-Conoce-las-nuevas-tecnicas-de-seleccion-de-personal-1024x576-1.png","type":"image\/png"}],"author":"Denis Pereta","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Denis Pereta","Temps estimat de lectura":"4 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/#article","isPartOf":{"@id":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/"},"author":{"name":"Denis Pereta","@id":"https:\/\/www.boomerang-intelligence.com\/ca\/#\/schema\/person\/b24d3c90f2bee8ea7a717afb3e0a3855"},"headline":"6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer","datePublished":"2026-01-09T12:31:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/"},"wordCount":730,"publisher":{"@id":"https:\/\/www.boomerang-intelligence.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.boomerang-intelligence.com\/wp-content\/uploads\/2026\/01\/146-Conoce-las-nuevas-tecnicas-de-seleccion-de-personal-1024x576-1.png","articleSection":["RRHH"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/","url":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/","name":"6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer - Boomerang Intelligence","isPartOf":{"@id":"https:\/\/www.boomerang-intelligence.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/#primaryimage"},"image":{"@id":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.boomerang-intelligence.com\/wp-content\/uploads\/2026\/01\/146-Conoce-las-nuevas-tecnicas-de-seleccion-de-personal-1024x576-1.png","datePublished":"2026-01-09T12:31:01+00:00","breadcrumb":{"@id":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/#primaryimage","url":"https:\/\/www.boomerang-intelligence.com\/wp-content\/uploads\/2026\/01\/146-Conoce-las-nuevas-tecnicas-de-seleccion-de-personal-1024x576-1.png","contentUrl":"https:\/\/www.boomerang-intelligence.com\/wp-content\/uploads\/2026\/01\/146-Conoce-las-nuevas-tecnicas-de-seleccion-de-personal-1024x576-1.png","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/rrhh\/6-nuevas-tecnicas-de-seleccion-de-personal-que-debes-conocer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.boomerang-intelligence.com\/ca\/"},{"@type":"ListItem","position":2,"name":"6 nuevas t\u00e9cnicas de selecci\u00f3n de personal que debes conocer"}]},{"@type":"WebSite","@id":"https:\/\/www.boomerang-intelligence.com\/ca\/#website","url":"https:\/\/www.boomerang-intelligence.com\/ca\/","name":"Boomerang Intelligence","description":"","publisher":{"@id":"https:\/\/www.boomerang-intelligence.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.boomerang-intelligence.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.boomerang-intelligence.com\/ca\/#organization","name":"Boomerang Intelligence","url":"https:\/\/www.boomerang-intelligence.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.boomerang-intelligence.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.boomerang-intelligence.com\/wp-content\/uploads\/2025\/09\/logo_boomerang_intelligence.png","contentUrl":"https:\/\/www.boomerang-intelligence.com\/wp-content\/uploads\/2025\/09\/logo_boomerang_intelligence.png","width":504,"height":130,"caption":"Boomerang Intelligence"},"image":{"@id":"https:\/\/www.boomerang-intelligence.com\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.boomerang-intelligence.com\/ca\/#\/schema\/person\/b24d3c90f2bee8ea7a717afb3e0a3855","name":"Denis Pereta","url":"https:\/\/www.boomerang-intelligence.com\/ca\/blog\/author\/denis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/posts\/3436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/comments?post=3436"}],"version-history":[{"count":1,"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/posts\/3436\/revisions"}],"predecessor-version":[{"id":3438,"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/posts\/3436\/revisions\/3438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/media\/3437"}],"wp:attachment":[{"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/media?parent=3436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/categories?post=3436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.boomerang-intelligence.com\/ca\/wp-json\/wp\/v2\/tags?post=3436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}